{"id":4269,"date":"2019-12-06T13:05:43","date_gmt":"2019-12-06T17:05:43","guid":{"rendered":"https:\/\/smokefreehousingondev.ca\/?page_id=4269"},"modified":"2025-09-18T14:12:26","modified_gmt":"2025-09-18T17:12:26","slug":"condominiums","status":"publish","type":"page","link":"https:\/\/smokefreehousingon.ca\/fr\/question-frequentes\/condominiums\/","title":{"rendered":"Condominiums"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4269\" class=\"elementor elementor-4269 elementor-3459\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d09aa50 e-con-full spacebullets e-flex e-con e-parent\" data-id=\"d09aa50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-020ca33 elementor-widget elementor-widget-heading\" data-id=\"020ca33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aspect juridique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a90c6a1 elementor-widget elementor-widget-jet-accordion\" data-id=\"a90c6a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1771\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1771\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Existe-t-il des lois provinciales ou municipales d\u2019interdiction du tabac qui s\u2019appliquent aux immeubles d\u2019appartements?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1771\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>La <a href=\"https:\/\/www.ontario.ca\/fr\/page\/les-endroits-ou-vous-ne-pouvez-pas-fumer-ou-vapoter-en-ontario\" target=\"_blank\" rel=\"noopener\"><i>Loi de 2017 favorisant un Ontario sans fum\u00e9e<\/i><\/a> interdit de fumer du tabac, d\u2019utiliser des cigarettes \u00e9lectroniques pour vapoter toute substance, et de fumer du cannabis (\u00e0 usage m\u00e9dical ou r\u00e9cr\u00e9atif) dans les zones communes des lieux publics. Cela inclut les zones communes int\u00e9rieures des condominiums, appartements et immeubles, y compris les couloirs, ascenseurs et buanderies.<\/p><p>Les administrations municipales ont le pouvoir d\u2019interdire ou de restreindre la fum\u00e9e ou le vapotage dans les lieux publics au sein de leurs limites g\u00e9ographiques, et de cr\u00e9er des r\u00e8glements municipaux sur le tabac qui surpassent la l\u00e9gislation sans fum\u00e9e de l\u2019Ontario. Communiquez avec votre municipalit\u00e9 pour savoir si de tels r\u00e8glements s\u2019appliquent \u00e0 votre immeuble.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1772\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1772\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Mon condominium peut-il l\u00e9galement adopter une politique sans fum\u00e9e pour les logements et balcons privatifs?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1772\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Oui. Il est l\u00e9gal pour un condominium d\u2019inclure une politique sans fum\u00e9e dans la d\u00e9claration, dans le r\u00e8glement administratif ou sous forme de r\u00e8gle. Les conseils d\u2019administration de condominium ont le pouvoir de prot\u00e9ger la sant\u00e9 et la s\u00e9curit\u00e9 de leurs r\u00e9sidents et de prot\u00e9ger leur propri\u00e9t\u00e9, tant que leur r\u00e8glement administratif n\u2019interf\u00e8re pas avec d\u2019autres lois f\u00e9d\u00e9rales ou provinciales.<\/p><p><strong>Ressources<\/strong><\/p><ul><li><a href=\"https:\/\/smokefreehousingon.ca\/fr\/condominiums\/lois-et-questions-dordre-juridique\/opinions-juridiques\/\">Section sur les opinions juridiques<\/a><\/li><li><a href=\"https:\/\/smokefreehousingon.ca\/wp-content\/uploads\/2015\/11\/on-condo-coop-protocol-2011.pdf\">How to implement a no-smoking policy for a multi-unit dwelling: A protocol for condominiums and housing co-operatives.<\/a><\/li><li>Regarder <a href=\"https:\/\/www.reminetwork.com\/videos\/smoke-free-condos\/\" target=\"_blank\" rel=\"noopener\">Smoke-free condos: Making legal sense of smoke-free policies<\/a>, un rapport vid\u00e9o pr\u00e9par\u00e9 par Condo Business.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1773\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1773\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Que faire si les r\u00e9sidents fument dans les zones communes?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1773\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Des agents d\u2019ex\u00e9cution de bureaux de sant\u00e9 publique locaux m\u00e8neront des inspections et enqu\u00eateront sur les plaintes relatives aux zones communes d\u2019appartements, de condominiums et de campus universitaires afin de faire appliquer la <i>Loi de 2017 favorisant un Ontario sans fum\u00e9e<\/i>. Appelez votre bureau de sant\u00e9 publique pour signaler une infraction \u00e0 la <i>Loi favorisant un Ontario sans fum\u00e9e<\/i>.<\/p><p>En vertu de la\u00a0<i>Loi de 2017 favorisant un Ontario sans fum\u00e9e<\/i>, les conseils d\u2019administration ont les responsabilit\u00e9s suivantes\u00a0:<\/p><ul><li>Veiller \u00e0 ce que tout le monde soit conscient que fumer est interdit dans les zones communes;<\/li><li>Retirer les cendriers et tout objet faisant office de cendrier;<\/li><li>Veiller \u00e0 ce que personne ne fume dans les zones communes de ces r\u00e9sidences;<\/li><li>Afficher des panneaux \u00ab\u00a0interdiction de fumer ou vapoter\u00a0\u00bb dans l\u2019ensemble des entr\u00e9es, sorties, toilettes, et autres lieux appropri\u00e9s.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1774\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"4\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1774\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Une politique sans fum\u00e9e interdit-elle l\u2019utilisation rituelle de tabac par les peuples autochtones ou autres groupes religieux?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1774\" class=\"jet-toggle__content\" data-toggle=\"4\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Les peuples autochtones utilisent du tabac traditionnel ou sacr\u00e9 depuis des milliers d\u2019ann\u00e9es. Le tabac traditionnel ou sacr\u00e9 diff\u00e8re du tabac commercial, car il est utilis\u00e9 de diverses mani\u00e8res y compris lors de c\u00e9r\u00e9monies ou rituels sacr\u00e9s de gu\u00e9rison ou de purification, et dans des coutumes sociales o\u00f9 il est donn\u00e9 ou \u00e9chang\u00e9 en signe de respect. Le tabac traditionnel ou sacr\u00e9 est cultiv\u00e9 et s\u00e9ch\u00e9 sans additifs.<\/p><p>L\u2019utilisation rituelle du tabac n\u2019est pas exclue des politiques sans fum\u00e9e dans les immeubles \u00e0 logements multiples, sauf indication contraire explicite. Cependant, selon la l\u00e9gislation sur les droits de la personne, tous les Ontariens ont le devoir de s\u2019adapter aux croyances et pratiques religieuses des autres. Le devoir d\u2019adaptation va dans les deux sens, car tout r\u00e9sident utilisant du tabac \u00e0 des fins rituelles doit s\u2019assurer de ne pas nuire ind\u00fbment aux autres r\u00e9sidents. Voici des conseils pour soutenir l\u2019utilisation rituelle du tabac\u00a0:<\/p><ol><li>Communiquer avec les locataires pour comprendre leur utilisation rituelle du tabac.<\/li><li>Se renseigner sur la dur\u00e9e et la fr\u00e9quence de l\u2019utilisation rituelle du tabac pr\u00e9vue.<\/li><li>Trouver des moyens de s\u2019adapter \u00e0 l\u2019utilisation rituelle du tabac qui n\u2019exposent pas d\u2019autres locataires \u00e0 la fum\u00e9e secondaire. Par exemple, si possible, recommander l\u2019utilisation \u00e0 l\u2019ext\u00e9rieur et \u00e9liminer tout obstacle pouvant emp\u00eacher la c\u00e9r\u00e9monie d\u2019avoir lieu dehors.<\/li><\/ol><p>Si l\u2019utilisation rituelle du tabac a lieu \u00e0 l\u2019int\u00e9rieur, \u00e9tablissez un syst\u00e8me de communication pour informer les autres r\u00e9sidents de l\u2019utilisation rituelle du tabac afin d\u2019\u00e9viter les plaintes, et \u00e9viter toute incompr\u00e9hension d\u2019ordre religieux ou culturel.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1775\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"5\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1775\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Les r\u00e9sidents non-fumeurs ont-ils un droit de respirer de l\u2019air pur \u00e0 l\u2019int\u00e9rieur?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1775\" class=\"jet-toggle__content\" data-toggle=\"5\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Aucun \u00ab\u00a0droit \u00e0 l\u2019air pur\u00a0\u00bb n\u2019est inscrit dans les lois canadiennes. En l\u2019absence d\u2019une politique sans fum\u00e9e, les r\u00e9sidents de condominium peuvent essayer de se prot\u00e9ger contre l\u2019exposition involontaire \u00e0 la fum\u00e9e secondaire en utilisant les r\u00e8gles g\u00e9n\u00e9rales de l\u2019association li\u00e9es \u00e0 la nuisance.<\/p><p>La nuisance est d\u00e9finie par une interf\u00e9rence d\u00e9raisonnable avec l\u2019utilisation et la jouissance de la propri\u00e9t\u00e9. Le test appropri\u00e9 pour d\u00e9terminer s\u2019il y a une nuisance concr\u00e8te implique l\u2019\u00e9quilibre entre l\u2019int\u00e9r\u00eat du plaignant et celui du d\u00e9fendeur. Pour prouver la nuisance, il n\u2019est pas n\u00e9cessaire de prouver l\u2019intention, la n\u00e9gligence ou la faute de la personne \u00e0 l\u2019origine de la nuisance. Cependant, le fait qu\u2019un conseil d\u2019administration de condominium reconnaisse ou non la fum\u00e9e secondaire comme une nuisance d\u00e9pendra vraiment de la formulation exacte de la r\u00e8gle du condominium relative \u00e0 la nuisance. Tr\u00e8s souvent, la r\u00e8gle sur la nuisance, m\u00eame si elle est r\u00e9dig\u00e9e en termes g\u00e9n\u00e9raux, s\u2019inscrit dans des contextes tr\u00e8s pr\u00e9cis comme les risques d\u2019incendie ou le bruit. La d\u00e9termination de s\u2019il y a nuisance couverte par la r\u00e8gle sur la nuisance ou non est tr\u00e8s souvent laiss\u00e9e \u00e0 la discr\u00e9tion du conseil d\u2019administration du condominium.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1776\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"6\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1776\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Les r\u00e9sidents qui fument ont-ils le droit de fumer dans leur logement, m\u00eame si la fum\u00e9e secondaire d\u00e9range les autres r\u00e9sidents?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1776\" class=\"jet-toggle__content\" data-toggle=\"6\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Il n\u2019existe pas de \u00ab\u00a0droit de fumer\u00a0\u00bb en tant que tel. Cependant, en l\u2019absence de politique sans fum\u00e9e, les r\u00e9sidents ont le droit de fumer dans leur logement.<\/p><p>Il faut insister sur le fait que ce droit n\u2019est pas absolu, et qu\u2019il est limit\u00e9 par le droit d\u2019autres personnes \u00e0 une\u00a0jouissance raisonnable\u00a0de leur propri\u00e9t\u00e9. Tandis qu\u2019une personne qui fume choisit d\u2019accepter les risques connus associ\u00e9s au tabagisme, elle n\u2019a pas le droit d\u2019imposer ces risques aux autres r\u00e9sidents de l\u2019immeuble. S\u2019il y a des preuves que la fum\u00e9e secondaire s\u2019infiltre dans un logement de mani\u00e8re fr\u00e9quente et continue, et qu\u2019elle interf\u00e8re consid\u00e9rablement avec l\u2019utilisation et la jouissance du logement, approchez le conseil d\u2019administration du condominium ou la personne qui fume pour en discuter.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1777\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"7\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1777\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Fumer peut-il \u00eatre consid\u00e9r\u00e9 comme un handicap?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1777\" class=\"jet-toggle__content\" data-toggle=\"7\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Cette question a \u00e9t\u00e9 trait\u00e9e \u00e0 plusieurs reprises au fil des ann\u00e9es, et les tribunaux canadiens ont toujours conclu (\u00e0 une exception pr\u00e8s) que la d\u00e9pendance \u00e0 la nicotine n\u2019est pas un handicap.<\/p><p>Dans le cas des r\u00e9sidences, m\u00eame si les personnes qui fument \u00e9taient jug\u00e9es comme un groupe prot\u00e9g\u00e9 au motif de leur d\u00e9pendance, elles seraient tenues de trouver des solutions de remplacement pour que leur d\u00e9pendance n\u2019expose pas leurs voisins et les passants \u00e0 la fum\u00e9e secondaire n\u00e9faste. Cela pourrait inclure de fumer \u00e0 l\u2019ext\u00e9rieur ou satisfaire leur d\u00e9pendance \u00e0 la nicotine par d\u2019autres moyens qui n\u2019\u00e9mettent pas de fum\u00e9e secondaire, comme de la gomme \u00e0 la nicotine, des pastilles de nicotine ou des inhalateurs de nicotine.<\/p><p>Il n\u2019y a pas de pr\u00e9c\u00e9dent juridique pour abroger une politique sans fum\u00e9e afin de s\u2019adapter \u00e0 un r\u00e9sident ayant une d\u00e9pendance \u00e0 la nicotine. Le fait qu\u2019une personne exerce sa libert\u00e9 de fumer ne signifie pas n\u00e9cessairement qu\u2019elle a un droit absolu de fumer sans tenir compte des autres r\u00e9sidents de l\u2019immeuble.<\/p><p>Une d\u00e9signation de handicap est tr\u00e8s individuelle. Si un arbitre venait \u00e0 d\u00e9cider qu\u2019un locataire fumeur \u00e9tait handicap\u00e9, cela ne signifie pas que tous les locataires qui fument, ou que tous les locataires en Ontario devraient aussi \u00eatre reconnus comme handicap\u00e9s.<\/p><p><strong>Ressources<\/strong><\/p><ul><li><a href=\"https:\/\/www.ontario.ca\/fr\/lois\/loi\/90h19\" target=\"_blank\" rel=\"noopener\">Code des droits de la personne de l\u2019Ontario, 1990<\/a><\/li><li><a href=\"http:\/\/www.ohrc.on.ca\/fr\/guide-concernant-vos-droits-et-responsabilit%25C3%25A9s-en-vertu-du-code-des-droits-de-la-personne-0\" target=\"_blank\" rel=\"noopener\">Guide concernant vos droits et responsabilit\u00e9s en vertu du Code des droits de la personne<\/a><span class=\"Apple-converted-space\">\u00a0<\/span><\/li><li><a href=\"https:\/\/smokefreehousingon.ca\/wp-content\/uploads\/2015\/12\/human_Rights_and_SF_MUDs.pdf\">Human Rights and No-Smoking Policies for Multi-Unit Dwellings.<\/a><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1778\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"8\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1778\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Les r\u00e9sidents peuvent-il fumer du cannabis m\u00e9dical dans leur logement?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1778\" class=\"jet-toggle__content\" data-toggle=\"8\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Les adaptations au cannabis m\u00e9dical doivent \u00eatre \u00e9tudi\u00e9es au cas par cas. Les adaptations d\u00e9pendent des faits et de la n\u00e9cessit\u00e9 de r\u00e9pondre aux besoins li\u00e9s \u00e0 la maladie de la personne en question. Voici des exemples d\u2019adaptation\u00a0:<\/p><ul><li>Fumer \u00e0 l\u2019ext\u00e9rieur<\/li><li>Utiliser des formes de cannabis autres que fumer, comme les vaporisateurs, les teintures, les comprim\u00e9s, ou les produits comestibles.<\/li><li>D\u00e9m\u00e9nager vers un logement avec un meilleur acc\u00e8s \u00e0 l\u2019ext\u00e9rieur.<\/li><\/ul><p>Pour justifier l\u2019action de fumer, plusieurs \u00e9l\u00e9ments devraient normalement \u00eatre \u00e9tablis, notamment\u00a0:<\/p><ol><li>Fumer est la m\u00e9thode prescrite au patient pour consommer du cannabis et obtenir l\u2019effet th\u00e9rapeutique souhait\u00e9 pour le traitement d\u2019un trouble ou des sympt\u00f4mes li\u00e9s \u00e0 un trouble \u2013 il est possible de demander des preuves m\u00e9dicales.<\/li><li>Fumer \u00e0 l\u2019ext\u00e9rieur est une contrainte trop importante (p.\u00a0ex. la personne n\u2019est pas mobile)<\/li><\/ol><p>Si les faits ci-dessus sont \u00e9tablis, le fournisseur de logement devra envisager de prendre des mesures d\u2019adaptation sans contrainte excessive. Un fournisseur de logement doit fournir un h\u00e9bergement, mais cela ne signifie pas n\u00e9cessairement que la personne a le droit de fumer dans son logement. De plus, il est important de se rappeler que des d\u00e9fis peuvent se pr\u00e9senter, qu\u2019ils soient fond\u00e9s ou non. Pour \u00e9viter les litiges, certains fournisseurs de logement peuvent simplement autoriser les locataires \u00e0 fumer du cannabis si leur statut m\u00e9dical peut \u00eatre d\u00e9montr\u00e9.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cde9f59 elementor-widget elementor-widget-heading\" data-id=\"cde9f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sant\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90fd6d6 elementor-widget elementor-widget-jet-accordion\" data-id=\"90fd6d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1521\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1521\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Quels sont les dangers de la fum\u00e9e secondaire?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1521\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Il n\u2019existe pas de niveau d\u2019exposition s\u00e9curitaire \u00e0 la fum\u00e9e secondaire. La fum\u00e9e secondaire contient plus de 50\u00a0substances chimiques canc\u00e9rig\u00e8nes et a \u00e9t\u00e9 d\u00e9sign\u00e9e comme un contaminant toxique de l\u2019air et agent canc\u00e9rig\u00e8ne connu.<\/p><p>Les personnes respirant de la fum\u00e9e secondaire pr\u00e9sentent un risque accru de\u00a0:<\/p><ul><li>Maladie cardiaque<\/li><li>Cancer du poumon<\/li><li>Emphys\u00e8me<\/li><li>Troubles respiratoires aigus (comme l\u2019asthme)<\/li><li>Infections pulmonaires<\/li><li>Toux excessive<\/li><li>Irritation de la gorge<\/li><\/ul><p>Les enfants \u00e0 na\u00eetre pr\u00e9sentent un risque accru de\u00a0:<\/p><ul><li>Faible poids \u00e0 la naissance<\/li><\/ul><p>Les b\u00e9b\u00e9s et enfants pr\u00e9sentent un risque accru de\u00a0:<\/p><ul><li>Mort subite du nourrisson<\/li><li>Asthme<\/li><li>Pneumonie<\/li><li>Bronchite<\/li><li>Laryngotrach\u00e9ite aigu\u00eb et toux<\/li><li>Otites<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1522\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1522\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Les filtres \u00e0 air, purificateurs ou syst\u00e8mes de ventilation peuvent-ils purifier l\u2019air des toxines de la fum\u00e9e secondaire?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1522\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><ul><li>Bien qu\u2019ils puissent att\u00e9nuer ses risques, les filtres \u00e0 air, purificateurs et syst\u00e8mes de ventilation ne peuvent pas \u00e9liminer la fum\u00e9e secondaire. Une partie de la fum\u00e9e et des plus grosses particules dans l\u2019air peuvent \u00eatre \u00e9limin\u00e9es, mais ils n\u2019\u00e9limineront pas les plus petites particules ou les gaz pr\u00e9sents dans la fum\u00e9e secondaire.<\/li><li>Lire l\u2019information de\u00a0<a href=\"https:\/\/www.canada.ca\/fr\/sante-canada\/services\/tabagisme-et-tabac\/eviter-fumee-secondaire\/eliminer-fumee-secondaire.html\" target=\"_blank\" rel=\"noopener\">Sant\u00e9 Canada<\/a>\u00a0au sujet de la fum\u00e9e secondaire et des filtres \u00e0 air, purificateurs et syst\u00e8mes de ventilation. Pour de plus amples renseignements \u00e0 propos de la ventilation et de la fum\u00e9e secondaire, consultez le <a href=\"https:\/\/www.cdc.gov\/tobacco\/secondhand-smoke\/home.html?utm\" target=\"_blank\" rel=\"noopener\">site des Centers for Disease Control<\/a>.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d90e7a1 elementor-widget elementor-widget-heading\" data-id=\"d90e7a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Autre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b521266 elementor-widget elementor-widget-jet-accordion\" data-id=\"b521266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1891\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1891\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><\/div><div class=\"jet-toggle__label-text\">Existe-t-il des condominiums sans fum\u00e9e en Ontario?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1891\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Le <a href=\"https:\/\/smokefreehousingon.ca\/fr\/repertoire-des-habitations-sans-fumee\/\">R\u00e9pertoire des habitations sans fum\u00e9e<\/a> peut vous aider \u00e0 trouver un logement sans fum\u00e9e. Il \u00e9num\u00e8re les logements priv\u00e9s, les logements sans but lucratif, les condominiums, les coop\u00e9ratives et les immeubles de location qui sont devenus sans fum\u00e9e ou sont en train le devenir, et est mis \u00e0 jour continuellement.<\/p><p>Consultez des <a href=\"https:\/\/smokefreehousingon.ca\/fr\/condominiums\/exemples-de-reussite\/\">exemples<\/a> de condominiums sans fum\u00e9e<\/p><p><a href=\"https:\/\/smokefreehousingon.ca\/fr\/nous-joindre\/\">Communiquez avec nous<\/a>\u00a0si vous connaissez un condominium qui a une politique sans fum\u00e9e en place.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aspect juridique Existe-t-il des lois provinciales ou municipales d\u2019interdiction du tabac qui s\u2019appliquent aux immeubles d\u2019appartements? La Loi de 2017 favorisant un Ontario sans fum\u00e9e interdit de fumer du tabac, d\u2019utiliser des cigarettes \u00e9lectroniques pour vapoter toute substance, et de fumer du cannabis (\u00e0 usage m\u00e9dical ou r\u00e9cr\u00e9atif) dans les zones communes des lieux publics. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4183,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"footnotes":""},"class_list":["post-4269","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/pages\/4269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/comments?post=4269"}],"version-history":[{"count":3,"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/pages\/4269\/revisions"}],"predecessor-version":[{"id":6439,"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/pages\/4269\/revisions\/6439"}],"up":[{"embeddable":true,"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/pages\/4183"}],"wp:attachment":[{"href":"https:\/\/smokefreehousingon.ca\/fr\/wp-json\/wp\/v2\/media?parent=4269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}